{"id":69,"date":"2025-11-24T11:09:37","date_gmt":"2025-11-24T11:09:37","guid":{"rendered":"https:\/\/www.csainstruments.com\/?page_id=69"},"modified":"2025-12-10T10:11:26","modified_gmt":"2025-12-10T10:11:26","slug":"strumentazione-di-controllo-e-processo","status":"publish","type":"page","link":"https:\/\/www.csainstruments.com\/en\/strumentazione-di-controllo-e-processo\/","title":{"rendered":"Technical Instruments"},"content":{"rendered":"<div class=\"wp-block-cover alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"470\" class=\"wp-block-cover__image-background wp-image-434 size-full\" alt=\"\" src=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumen.-controllo.jpg\" style=\"object-position:50% 80%\" data-object-fit=\"cover\" data-object-position=\"50% 80%\" srcset=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumen.-controllo.jpg 780w, https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumen.-controllo-300x181.jpg 300w, https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumen.-controllo-768x463.jpg 768w, https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumen.-controllo-18x12.jpg 18w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-ast-global-color-8-background-color has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h1 class=\"wp-block-heading has-text-align-center has-text-color has-link-color has-large-font-size wp-elements-1\" style=\"color:#8be7ff\">Technical instruments<\/h1>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">CSAI 5.0 is a distributor and agent of top-tier brands for the following command and control instrumentation:<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\"><strong>Flow, Pressure, Temperature, Level, Ambient Gas Detection, and Weighing Systems <\/strong>(scales and load cells) suitable for both safe areas and ATEX environments.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-ast-global-color-4-color has-text-color has-background has-link-color wp-elements-2 is-layout-constrained wp-block-group-is-layout-constrained\" style=\"border-radius:52px;background-color:#13486c\">\n<h2 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-3 translation-block\" style=\"font-size:30px\">Flow Measurement Instruments<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:300px\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"138\" src=\"http:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/11\/port2.png\" alt=\"\" class=\"wp-image-254\" style=\"aspect-ratio:1;object-fit:contain;width:150px\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Flow Meters<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>Ultrasonic flow meters<\/li>\n\n\n\n<li>Thermal flow meters<\/li>\n\n\n\n<li>Coriolis mass flow meters<\/li>\n\n\n\n<li>Vortex flow meters<\/li>\n\n\n\n<li>Variable area air flow meters<\/li>\n\n\n\n<li>Magnetic flow meters<\/li>\n\n\n\n<li>Float flow meters<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-4 translation-block\" style=\"font-size:30px\">Pressure Measurement Instruments<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:300px\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"302\" height=\"309\" src=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/11\/pressione1.png\" alt=\"\" class=\"wp-image-259\" style=\"aspect-ratio:1;object-fit:cover;width:150px\" srcset=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/11\/pressione1.png 302w, https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/11\/pressione1-293x300.png 293w\" sizes=\"auto, (max-width: 302px) 100vw, 302px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pressure Gauges<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>Analog and digital spring or diaphragm gauges<\/li>\n\n\n\n<li>Differential pressure gauges<\/li>\n\n\n\n<li>Pressure transmitters<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-5 translation-block\" style=\"font-size:30px\">Temperature Measurement Instruments<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:300px\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"124\" height=\"123\" src=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/11\/temp1.png\" alt=\"\" class=\"wp-image-260\" style=\"aspect-ratio:1;object-fit:cover;width:150px\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Thermometers<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>Liquid and digital thermometers<\/li>\n\n\n\n<li>Thermocouples<\/li>\n\n\n\n<li>Thermistors<\/li>\n\n\n\n<li>Infrared thermometers<\/li>\n\n\n\n<li>Thermal cameras<\/li>\n\n\n\n<li>Strip thermometers<\/li>\n\n\n\n<li>Contact thermometers<\/li>\n\n\n\n<li>Datalogger<\/li>\n\n\n\n<li>Bulb thermometers<\/li>\n\n\n\n<li>Gas thermometers<\/li>\n\n\n\n<li>Probe thermometers<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-6 translation-block\" style=\"font-size:30px\">Level Measurement Instruments<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:300px\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"269\" height=\"183\" src=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/11\/liv1.png\" alt=\"\" class=\"wp-image-262\" style=\"aspect-ratio:1;object-fit:contain;width:150px\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Indicators, Sensors, Level Switches<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>Magnetic level indicators<\/li>\n\n\n\n<li>Column level indicators<\/li>\n\n\n\n<li>LED level indicators<\/li>\n\n\n\n<li>Capacitive level sensors<\/li>\n\n\n\n<li>Ultrasonic level sensors<\/li>\n\n\n\n<li>Radar level sensors<\/li>\n\n\n\n<li>Float level sensors<\/li>\n\n\n\n<li>Vibration level sensors<\/li>\n\n\n\n<li>Optical level sensors<\/li>\n\n\n\n<li>Float level switches<\/li>\n\n\n\n<li>Optoelectronic level switches<\/li>\n\n\n\n<li>Vibration level switches<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-7 translation-block\" style=\"font-size:30px\">Ambient Gas Measurement Instruments<\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:300px\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"409\" src=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumento-misure-gas.jpg\" alt=\"\" class=\"wp-image-436\" style=\"aspect-ratio:1;object-fit:cover;width:150px\" srcset=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumento-misure-gas.jpg 900w, https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumento-misure-gas-300x136.jpg 300w, https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumento-misure-gas-768x349.jpg 768w, https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumento-misure-gas-18x8.jpg 18w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Detectors and Control Units<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>Fixed and portable gas detectors for indoor and outdoor use&nbsp;<\/li>\n\n\n\n<li>Catalytic sensor detectors<\/li>\n\n\n\n<li>Threshold detectors<\/li>\n\n\n\n<li>Infrared sensor detectors<\/li>\n\n\n\n<li>Electrochemical detectors<\/li>\n\n\n\n<li>Control units<\/li>\n\n\n\n<li>Gas detection kits<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<h3 class=\"wp-block-heading has-ast-global-color-4-color has-text-color has-link-color wp-elements-8 translation-block\" style=\"font-size:30px\">Weighing System Instruments<\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:300px\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"519\" height=\"393\" src=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/11\/bilancia-1.jpg\" alt=\"\" class=\"wp-image-264\" style=\"aspect-ratio:1;object-fit:cover;width:150px\" srcset=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/11\/bilancia-1.jpg 519w, https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/11\/bilancia-1-300x227.jpg 300w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Scales and Systems<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>Load cells<\/li>\n\n\n\n<li>Bench and conveyor belt scales<\/li>\n\n\n\n<li>Complete weighing systems&nbsp;<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\">Contacts<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Technical Instruments division:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:f.iniziato@csainstruments.com\">f.iniziato@csainstruments.com<\/a><br><a href=\"mailto:u.napolitano@csainstruments.com\">u.napolitano@csainstruments.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">General Information:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:info@csainstruments.com\">info@csainstruments.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Administration:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:d.scampone@csainstruments.com\">d.scampone@csainstruments.com<\/a><br><a href=\"mailto:amministrazione@csainstruments.com\">amministrazione@csainstruments.com<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>CSAI 5.0 \u00e8 distributore e agente di brand di altissimo livello circa la seguente strumentazione di comando e controllo: Portata, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-69","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Strumentazione di Controllo e Processo - CSAI 5.0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csainstruments.com\/en\/strumentazione-di-controllo-e-processo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Strumentazione di Controllo e Processo - CSAI 5.0\" \/>\n<meta property=\"og:description\" content=\"CSAI 5.0 \u00e8 distributore e agente di brand di altissimo livello circa la seguente strumentazione di comando e controllo: Portata, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csainstruments.com\/en\/strumentazione-di-controllo-e-processo\/\" \/>\n<meta property=\"og:site_name\" content=\"CSAI 5.0\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T10:11:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumen.-controllo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/strumentazione-di-controllo-e-processo\\\/\",\"url\":\"https:\\\/\\\/www.csainstruments.com\\\/strumentazione-di-controllo-e-processo\\\/\",\"name\":\"Strumentazione di Controllo e Processo - CSAI 5.0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/strumentazione-di-controllo-e-processo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/strumentazione-di-controllo-e-processo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.csainstruments.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/strumen.-controllo.jpg\",\"datePublished\":\"2025-11-24T11:09:37+00:00\",\"dateModified\":\"2025-12-10T10:11:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/strumentazione-di-controllo-e-processo\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.csainstruments.com\\\/strumentazione-di-controllo-e-processo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/strumentazione-di-controllo-e-processo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.csainstruments.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/strumen.-controllo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.csainstruments.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/strumen.-controllo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/strumentazione-di-controllo-e-processo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.csainstruments.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Strumentazione di Controllo e Processo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/#website\",\"url\":\"https:\\\/\\\/www.csainstruments.com\\\/\",\"name\":\"CSAI 5.0\",\"description\":\"Control System Automation Instruments\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.csainstruments.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/#organization\",\"name\":\"CSAI 5.0\",\"url\":\"https:\\\/\\\/www.csainstruments.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.csainstruments.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cropped-CSAI-vector.png\",\"contentUrl\":\"https:\\\/\\\/www.csainstruments.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cropped-CSAI-vector.png\",\"width\":403,\"height\":121,\"caption\":\"CSAI 5.0\"},\"image\":{\"@id\":\"https:\\\/\\\/www.csainstruments.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/csai50\\\/?originalSubdomain=it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Strumentazione di Controllo e Processo - CSAI 5.0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csainstruments.com\/en\/strumentazione-di-controllo-e-processo\/","og_locale":"en_GB","og_type":"article","og_title":"Strumentazione di Controllo e Processo - CSAI 5.0","og_description":"CSAI 5.0 \u00e8 distributore e agente di brand di altissimo livello circa la seguente strumentazione di comando e controllo: Portata, [&hellip;]","og_url":"https:\/\/www.csainstruments.com\/en\/strumentazione-di-controllo-e-processo\/","og_site_name":"CSAI 5.0","article_modified_time":"2025-12-10T10:11:26+00:00","og_image":[{"width":780,"height":470,"url":"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumen.-controllo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csainstruments.com\/strumentazione-di-controllo-e-processo\/","url":"https:\/\/www.csainstruments.com\/strumentazione-di-controllo-e-processo\/","name":"Strumentazione di Controllo e Processo - CSAI 5.0","isPartOf":{"@id":"https:\/\/www.csainstruments.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.csainstruments.com\/strumentazione-di-controllo-e-processo\/#primaryimage"},"image":{"@id":"https:\/\/www.csainstruments.com\/strumentazione-di-controllo-e-processo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumen.-controllo.jpg","datePublished":"2025-11-24T11:09:37+00:00","dateModified":"2025-12-10T10:11:26+00:00","breadcrumb":{"@id":"https:\/\/www.csainstruments.com\/strumentazione-di-controllo-e-processo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csainstruments.com\/strumentazione-di-controllo-e-processo\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.csainstruments.com\/strumentazione-di-controllo-e-processo\/#primaryimage","url":"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumen.-controllo.jpg","contentUrl":"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/strumen.-controllo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.csainstruments.com\/strumentazione-di-controllo-e-processo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.csainstruments.com\/"},{"@type":"ListItem","position":2,"name":"Strumentazione di Controllo e Processo"}]},{"@type":"WebSite","@id":"https:\/\/www.csainstruments.com\/#website","url":"https:\/\/www.csainstruments.com\/","name":"CSAI 5.0","description":"Control System Automation Instruments","publisher":{"@id":"https:\/\/www.csainstruments.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csainstruments.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.csainstruments.com\/#organization","name":"CSAI 5.0","url":"https:\/\/www.csainstruments.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.csainstruments.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/cropped-CSAI-vector.png","contentUrl":"https:\/\/www.csainstruments.com\/wp-content\/uploads\/2025\/12\/cropped-CSAI-vector.png","width":403,"height":121,"caption":"CSAI 5.0"},"image":{"@id":"https:\/\/www.csainstruments.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/csai50\/?originalSubdomain=it"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.csainstruments.com\/en\/wp-json\/wp\/v2\/pages\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csainstruments.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.csainstruments.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.csainstruments.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csainstruments.com\/en\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":15,"href":"https:\/\/www.csainstruments.com\/en\/wp-json\/wp\/v2\/pages\/69\/revisions"}],"predecessor-version":[{"id":523,"href":"https:\/\/www.csainstruments.com\/en\/wp-json\/wp\/v2\/pages\/69\/revisions\/523"}],"wp:attachment":[{"href":"https:\/\/www.csainstruments.com\/en\/wp-json\/wp\/v2\/media?parent=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}